{"id":436773,"date":"2025-12-06T11:31:49","date_gmt":"2025-12-06T10:31:49","guid":{"rendered":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/"},"modified":"2026-03-28T18:31:24","modified_gmt":"2026-03-28T17:31:24","slug":"veul-gere-deur-de-achterdeur","status":"publish","type":"product","link":"https:\/\/orkestbandenkopen.nl\/en\/winkel\/veul-gere-deur-de-achterdeur\/","title":{"rendered":"Veul Ge\u0300re &#8211; Deur de achterdeur (2:59)"},"content":{"rendered":"<p><iframe title=\"Veul G\u00e8re -  Deur de Achterdeur! (Carnaval 2025)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/dOqbXDPlXVI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p><audio class=\"wp-audio-shortcode\" id=\"audio-436773-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/s3-eu-west-1.amazonaws.com\/publieke-bestanden\/mp3_samples\/veul-gere-deur-de-achterdeur.mp3?_=1\" \/><a href=\"https:\/\/s3-eu-west-1.amazonaws.com\/publieke-bestanden\/mp3_samples\/veul-gere-deur-de-achterdeur.mp3\">https:\/\/s3-eu-west-1.amazonaws.com\/publieke-bestanden\/mp3_samples\/veul-gere-deur-de-achterdeur.mp3<\/a><\/audio><\/p>","protected":false},"featured_media":14,"template":"","meta":[],"product_brand":[],"product_cat":[2981],"product_tag":[],"class_list":{"0":"post-436773","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zonder-backing","7":"pa_artiest-veul-gere","8":"pa_genre-carnaval","9":"pa_jaar-van-release-3158","10":"pa_nationaliteit-artiest-nederland","11":"pa_periode-release-2020-2029","12":"pa_taal-nederlands","14":"first","15":"instock","16":"downloadable","17":"virtual","18":"sold-individually","19":"taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orkestband Veul Ge\u0300re - Deur de achterdeur (2:59)<\/title>\n<meta name=\"description\" content=\"Orkestband \/ Instrumentale versie \/ karaoke van Veul Ge\u0300re - Deur de achterdeur (2:59). Ons motto, kwaliteit voor kwantiteit!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orkestbandenkopen.nl\/en\/shop\/veul-gere-deur-de-achterdeur\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orkestband Veul Ge\u0300re - Deur de achterdeur (2:59)\" \/>\n<meta property=\"og:description\" content=\"Orkestband \/ Instrumentale versie \/ karaoke van Veul Ge\u0300re - Deur de achterdeur (2:59). Ons motto, kwaliteit voor kwantiteit!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orkestbandenkopen.nl\/en\/shop\/veul-gere-deur-de-achterdeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Orkestbandenkopen.nl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T17:31:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/07\/carnaval.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/\",\"url\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/\",\"name\":\"Orkestband Veul Ge\u0300re - Deur de achterdeur (2:59)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/carnaval.png\",\"datePublished\":\"2025-12-06T10:31:49+00:00\",\"dateModified\":\"2026-03-28T17:31:24+00:00\",\"description\":\"Orkestband \\\/ Instrumentale versie \\\/ karaoke van Veul Ge\u0300re - Deur de achterdeur (2:59). Ons motto, kwaliteit voor kwantiteit!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/carnaval.png\",\"contentUrl\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/carnaval.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/winkel\\\/veul-gere-deur-de-achterdeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Veul Ge\u0300re &#8211; Deur de achterdeur (2:59)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/#website\",\"url\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/\",\"name\":\"Orkestbandenkopen.nl\",\"description\":\"Orkestbandenkopen.nl \\\/ Karaokeplaybacks.de \\\/ Karaokeplaybacks.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/#organization\",\"name\":\"Orkestbandenkopen.nl\",\"url\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/orkestbanden-1.png\",\"contentUrl\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/orkestbanden-1.png\",\"width\":581,\"height\":81,\"caption\":\"Orkestbandenkopen.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/orkestbandenkopen.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orkestband Veul Ge\u0300re - Deur de achterdeur (2:59)","description":"Orkestband \/ Instrumentale versie \/ karaoke van Veul Ge\u0300re - Deur de achterdeur (2:59). Ons motto, kwaliteit voor kwantiteit!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orkestbandenkopen.nl\/en\/shop\/veul-gere-deur-de-achterdeur\/","og_locale":"en_GB","og_type":"article","og_title":"Orkestband Veul Ge\u0300re - Deur de achterdeur (2:59)","og_description":"Orkestband \/ Instrumentale versie \/ karaoke van Veul Ge\u0300re - Deur de achterdeur (2:59). Ons motto, kwaliteit voor kwantiteit!","og_url":"https:\/\/orkestbandenkopen.nl\/en\/shop\/veul-gere-deur-de-achterdeur\/","og_site_name":"Orkestbandenkopen.nl","article_modified_time":"2026-03-28T17:31:24+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/07\/carnaval.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/","url":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/","name":"Orkestband Veul Ge\u0300re - Deur de achterdeur (2:59)","isPartOf":{"@id":"https:\/\/orkestbandenkopen.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/#primaryimage"},"image":{"@id":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/#primaryimage"},"thumbnailUrl":"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/07\/carnaval.png","datePublished":"2025-12-06T10:31:49+00:00","dateModified":"2026-03-28T17:31:24+00:00","description":"Orkestband \/ Instrumentale versie \/ karaoke van Veul Ge\u0300re - Deur de achterdeur (2:59). Ons motto, kwaliteit voor kwantiteit!","breadcrumb":{"@id":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/#primaryimage","url":"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/07\/carnaval.png","contentUrl":"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/07\/carnaval.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/orkestbandenkopen.nl\/winkel\/veul-gere-deur-de-achterdeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orkestbandenkopen.nl\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/orkestbandenkopen.nl\/shop\/"},{"@type":"ListItem","position":3,"name":"Veul Ge\u0300re &#8211; Deur de achterdeur (2:59)"}]},{"@type":"WebSite","@id":"https:\/\/orkestbandenkopen.nl\/#website","url":"https:\/\/orkestbandenkopen.nl\/","name":"Instrumentalkaraokesongs.com","description":"Orchestrabandskopen.co.uk \/ Karaokeplaybacks.de \/ Karaokeplaybacks.com","publisher":{"@id":"https:\/\/orkestbandenkopen.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orkestbandenkopen.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/orkestbandenkopen.nl\/#organization","name":"Instrumentalkaraokesongs.com","url":"https:\/\/orkestbandenkopen.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/orkestbandenkopen.nl\/#\/schema\/logo\/image\/","url":"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/04\/orkestbanden-1.png","contentUrl":"https:\/\/orkestbandenkopen.nl\/wp-content\/uploads\/2024\/04\/orkestbanden-1.png","width":581,"height":81,"caption":"Orkestbandenkopen.nl"},"image":{"@id":"https:\/\/orkestbandenkopen.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/product\/436773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/media\/14"}],"wp:attachment":[{"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/media?parent=436773"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/product_brand?post=436773"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/product_cat?post=436773"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/orkestbandenkopen.nl\/en\/wp-json\/wp\/v2\/product_tag?post=436773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}